{"id":30,"count":18,"description":"","link":"https:\/\/fuchstransporte.org\/en\/event-kategorie\/partner-konvoi\/","name":"Partner-Konvoi","slug":"partner-konvoi","taxonomy":"mec_category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Partner-Konvoi Archives | Fuchs Transporte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fuchstransporte.org\/en\/event-kategorie\/partner-konvoi\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Partner-Konvoi Archives | Fuchs Transporte\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fuchstransporte.org\/en\/event-kategorie\/partner-konvoi\/\" \/>\n<meta property=\"og:site_name\" content=\"Fuchs Transporte\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/fuchstransporte.org\\\/event-kategorie\\\/partner-konvoi\\\/\",\"url\":\"https:\\\/\\\/fuchstransporte.org\\\/event-kategorie\\\/partner-konvoi\\\/\",\"name\":\"Partner-Konvoi Archives | Fuchs Transporte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fuchstransporte.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fuchstransporte.org\\\/event-kategorie\\\/partner-konvoi\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fuchstransporte.org\\\/event-kategorie\\\/partner-konvoi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/fuchstransporte.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Partner-Konvoi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fuchstransporte.org\\\/#website\",\"url\":\"https:\\\/\\\/fuchstransporte.org\\\/\",\"name\":\"Fuchs Transporte\",\"description\":\"Die Profis im Transport! | VTC\",\"publisher\":{\"@id\":\"https:\\\/\\\/fuchstransporte.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fuchstransporte.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/fuchstransporte.org\\\/#organization\",\"name\":\"Fuchs Transporte GmbH (Virtuell Spedition)\",\"url\":\"https:\\\/\\\/fuchstransporte.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/fuchstransporte.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/fuchstransporte.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/IMG_20220610_193129.png?fit=2633%2C1828&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/fuchstransporte.org\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/IMG_20220610_193129.png?fit=2633%2C1828&ssl=1\",\"width\":2633,\"height\":1828,\"caption\":\"Fuchs Transporte GmbH (Virtuell Spedition)\"},\"image\":{\"@id\":\"https:\\\/\\\/fuchstransporte.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCbsfFGQaJpYplT5ek18gXnw\",\"https:\\\/\\\/www.instagram.com\\\/ft_fuchstransporte\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Partner-Konvoi Archives | Fuchs Transporte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fuchstransporte.org\/en\/event-kategorie\/partner-konvoi\/","og_locale":"en_GB","og_type":"article","og_title":"Partner-Konvoi Archives | Fuchs Transporte","og_url":"https:\/\/fuchstransporte.org\/en\/event-kategorie\/partner-konvoi\/","og_site_name":"Fuchs Transporte","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/fuchstransporte.org\/event-kategorie\/partner-konvoi\/","url":"https:\/\/fuchstransporte.org\/event-kategorie\/partner-konvoi\/","name":"Partner-Konvoi Archives | Fuchs Transporte","isPartOf":{"@id":"https:\/\/fuchstransporte.org\/#website"},"breadcrumb":{"@id":"https:\/\/fuchstransporte.org\/event-kategorie\/partner-konvoi\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/fuchstransporte.org\/event-kategorie\/partner-konvoi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/fuchstransporte.org\/"},{"@type":"ListItem","position":2,"name":"Partner-Konvoi"}]},{"@type":"WebSite","@id":"https:\/\/fuchstransporte.org\/#website","url":"https:\/\/fuchstransporte.org\/","name":"Fuchs Transporte","description":"Die Profis im Transport! | VTC","publisher":{"@id":"https:\/\/fuchstransporte.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fuchstransporte.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/fuchstransporte.org\/#organization","name":"Fuchs Transporte GmbH (Virtuell Spedition)","url":"https:\/\/fuchstransporte.org\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/fuchstransporte.org\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/fuchstransporte.org\/wp-content\/uploads\/2022\/06\/IMG_20220610_193129.png?fit=2633%2C1828&ssl=1","contentUrl":"https:\/\/i0.wp.com\/fuchstransporte.org\/wp-content\/uploads\/2022\/06\/IMG_20220610_193129.png?fit=2633%2C1828&ssl=1","width":2633,"height":1828,"caption":"Fuchs Transporte GmbH (Virtuell Spedition)"},"image":{"@id":"https:\/\/fuchstransporte.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.youtube.com\/channel\/UCbsfFGQaJpYplT5ek18gXnw","https:\/\/www.instagram.com\/ft_fuchstransporte\/"]}]}},"_links":{"self":[{"href":"https:\/\/fuchstransporte.org\/en\/wp-json\/wp\/v2\/mec_category\/30","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fuchstransporte.org\/en\/wp-json\/wp\/v2\/mec_category"}],"about":[{"href":"https:\/\/fuchstransporte.org\/en\/wp-json\/wp\/v2\/taxonomies\/mec_category"}],"wp:post_type":[{"href":"https:\/\/fuchstransporte.org\/en\/wp-json\/wp\/v2\/mec-events?mec_category=30"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}